{"id":20931,"date":"2023-04-19T09:00:54","date_gmt":"2023-04-19T09:00:54","guid":{"rendered":"https:\/\/massalagros.com\/?p=20931"},"modified":"2023-04-14T09:04:02","modified_gmt":"2023-04-14T09:04:02","slug":"espace-gourmand","status":"publish","type":"post","link":"https:\/\/massalagros.com\/fr\/blog\/espace-gourmand\/","title":{"rendered":"Espace gourmand et cuisine biologique au Mas Salagros"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":21120,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[215],"tags":[571,604,700,607,570,545,559,548],"class_list":["post-20931","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gastronomie-blog","tag-activites","tag-degustation-de-vins","tag-espace-gourmand","tag-gourmande","tag-hotels-ecologiques","tag-mas-salagros-ecoresort-fr","tag-tourisme-durable","tag-week-end-romantique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Espace gourmand : notre s\u00e9lection - Blog | Mas Salagros<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez l\u2019espace gourmand du Mas Salagros, o\u00f9 l\u2019on y propose une cuisine biologique du terroir pour une exp\u00e9rience culinaire unique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/massalagros.com\/fr\/blog\/espace-gourmand\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Espace gourmand : notre s\u00e9lection - Blog | Mas Salagros\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez l\u2019espace gourmand du Mas Salagros, o\u00f9 l\u2019on y propose une cuisine biologique du terroir pour une exp\u00e9rience culinaire unique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/massalagros.com\/fr\/blog\/espace-gourmand\/\" \/>\n<meta property=\"og:site_name\" content=\"Mas Salagros\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MasSalagros\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-19T09:00:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/massalagros.com\/wp-content\/uploads\/2023\/04\/espace-gourmand.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"412\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mariona Mallafr\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MasSalagros\" \/>\n<meta name=\"twitter:site\" content=\"@MasSalagros\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mariona Mallafr\u00e9\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/massalagros.com\\\/fr\\\/blog\\\/espace-gourmand\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/massalagros.com\\\/fr\\\/blog\\\/espace-gourmand\\\/\"},\"author\":{\"name\":\"Mariona Mallafr\u00e9\",\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/fr\\\/#\\\/schema\\\/person\\\/3773f2547b939ef33bcc2be351034752\"},\"headline\":\"Espace gourmand et cuisine biologique au Mas Salagros\",\"datePublished\":\"2023-04-19T09:00:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/massalagros.com\\\/fr\\\/blog\\\/espace-gourmand\\\/\"},\"wordCount\":8,\"publisher\":{\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/massalagros.com\\\/fr\\\/blog\\\/espace-gourmand\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/massalagros.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/espace-gourmand.jpg\",\"keywords\":[\"activit\u00e9s\",\"d\u00e9gustation de vins\",\"espace gourmand\",\"Gourmande\",\"h\u00f4tels \u00e9cologiques\",\"Mas Salagros EcoResort\",\"tourisme durable\",\"week-end romantique\"],\"articleSection\":[\"Gastronomie\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/massalagros.com\\\/fr\\\/blog\\\/espace-gourmand\\\/\",\"url\":\"https:\\\/\\\/massalagros.com\\\/fr\\\/blog\\\/espace-gourmand\\\/\",\"name\":\"Espace gourmand : notre s\u00e9lection - Blog | Mas Salagros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/massalagros.com\\\/fr\\\/blog\\\/espace-gourmand\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/massalagros.com\\\/fr\\\/blog\\\/espace-gourmand\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/massalagros.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/espace-gourmand.jpg\",\"datePublished\":\"2023-04-19T09:00:54+00:00\",\"description\":\"D\u00e9couvrez l\u2019espace gourmand du Mas Salagros, o\u00f9 l\u2019on y propose une cuisine biologique du terroir pour une exp\u00e9rience culinaire unique.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/massalagros.com\\\/fr\\\/blog\\\/espace-gourmand\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/massalagros.com\\\/fr\\\/blog\\\/espace-gourmand\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/massalagros.com\\\/fr\\\/blog\\\/espace-gourmand\\\/#primaryimage\",\"url\":\"https:\\\/\\\/massalagros.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/espace-gourmand.jpg\",\"contentUrl\":\"https:\\\/\\\/massalagros.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/espace-gourmand.jpg\",\"width\":800,\"height\":412,\"caption\":\"espace gourmand\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/massalagros.com\\\/fr\\\/blog\\\/espace-gourmand\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/massalagros.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Espace gourmand et cuisine biologique au Mas Salagros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.massalagros.com\\\/fr\\\/\",\"name\":\"Mas Salagros\",\"description\":\"EcoResort de lujo en Barcelona - Vallromanes\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.massalagros.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/fr\\\/#organization\",\"name\":\"MAS SALAGROS HOTEL ECORESORT\",\"url\":\"https:\\\/\\\/www.massalagros.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/IMG_0116.jpg\",\"contentUrl\":\"\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/IMG_0116.jpg\",\"width\":2000,\"height\":1333,\"caption\":\"MAS SALAGROS HOTEL ECORESORT\"},\"image\":{\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MasSalagros\\\/\",\"https:\\\/\\\/x.com\\\/MasSalagros\",\"https:\\\/\\\/www.instagram.com\\\/massalagrosecoresort\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/fr\\\/#\\\/schema\\\/person\\\/3773f2547b939ef33bcc2be351034752\",\"name\":\"Mariona Mallafr\u00e9\",\"description\":\"\u00a1Hola! Soy Mariona. Luego de graduarme en Publicidad y Relaciones P\u00fablicas en la Universidad Abat Oliba CEU, he acumulado a\u00f1os de experiencia trabajando en agencias de publicidad y comunicaci\u00f3n, especializ\u00e1ndome en los sectores de Turismo y Lifestyle. Mi trayectoria dio un giro emocionante a principios de 2017 al unirme al equipo de Mas Salagros, un proyecto innovador que lidera el turismo ecol\u00f3gico y sostenible en Espa\u00f1a. En este contexto, he tenido la responsabilidad de concebir, dirigir e implementar toda la estrategia de comunicaci\u00f3n y marketing. Lo que m\u00e1s me apasiona de mi labor en Mas Salagros es la oportunidad de desarrollar estrategias de comunicaci\u00f3n y marketing que contribuyan a nuestro principal objetivo: fomentar el turismo responsable y sostenible. Esta pasi\u00f3n me llev\u00f3 a complementar mis estudios con un m\u00e1ster en la prestigiosa escuela de negocios ISDI, especializada en la era digital, con el prop\u00f3sito de seguir aportando conocimientos digitales a un negocio tan innovador. Trabajar en Mas Salagros me permite crear experiencias personalizadas para cada cliente, haci\u00e9ndolos sentir \u00fanicos y cuidando hasta el \u00faltimo detalle. Este enfoque potencia mi creatividad, ya que las posibilidades son verdaderamente ilimitadas. Estoy emocionada por seguir contribuyendo al crecimiento de un negocio que comparte mis valores de sostenibilidad y excelencia en el servicio.\",\"url\":\"https:\\\/\\\/massalagros.com\\\/fr\\\/blog\\\/author\\\/mariona\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Espace gourmand : notre s\u00e9lection - Blog | Mas Salagros","description":"D\u00e9couvrez l\u2019espace gourmand du Mas Salagros, o\u00f9 l\u2019on y propose une cuisine biologique du terroir pour une exp\u00e9rience culinaire unique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/massalagros.com\/fr\/blog\/espace-gourmand\/","og_locale":"fr_FR","og_type":"article","og_title":"Espace gourmand : notre s\u00e9lection - Blog | Mas Salagros","og_description":"D\u00e9couvrez l\u2019espace gourmand du Mas Salagros, o\u00f9 l\u2019on y propose une cuisine biologique du terroir pour une exp\u00e9rience culinaire unique.","og_url":"https:\/\/massalagros.com\/fr\/blog\/espace-gourmand\/","og_site_name":"Mas Salagros","article_publisher":"https:\/\/www.facebook.com\/MasSalagros\/","article_published_time":"2023-04-19T09:00:54+00:00","og_image":[{"width":800,"height":412,"url":"https:\/\/massalagros.com\/wp-content\/uploads\/2023\/04\/espace-gourmand.jpg","type":"image\/jpeg"}],"author":"Mariona Mallafr\u00e9","twitter_card":"summary_large_image","twitter_creator":"@MasSalagros","twitter_site":"@MasSalagros","twitter_misc":{"\u00c9crit par":"Mariona Mallafr\u00e9"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/massalagros.com\/fr\/blog\/espace-gourmand\/#article","isPartOf":{"@id":"https:\/\/massalagros.com\/fr\/blog\/espace-gourmand\/"},"author":{"name":"Mariona Mallafr\u00e9","@id":"https:\/\/www.massalagros.com\/fr\/#\/schema\/person\/3773f2547b939ef33bcc2be351034752"},"headline":"Espace gourmand et cuisine biologique au Mas Salagros","datePublished":"2023-04-19T09:00:54+00:00","mainEntityOfPage":{"@id":"https:\/\/massalagros.com\/fr\/blog\/espace-gourmand\/"},"wordCount":8,"publisher":{"@id":"https:\/\/www.massalagros.com\/fr\/#organization"},"image":{"@id":"https:\/\/massalagros.com\/fr\/blog\/espace-gourmand\/#primaryimage"},"thumbnailUrl":"https:\/\/massalagros.com\/wp-content\/uploads\/2023\/04\/espace-gourmand.jpg","keywords":["activit\u00e9s","d\u00e9gustation de vins","espace gourmand","Gourmande","h\u00f4tels \u00e9cologiques","Mas Salagros EcoResort","tourisme durable","week-end romantique"],"articleSection":["Gastronomie"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/massalagros.com\/fr\/blog\/espace-gourmand\/","url":"https:\/\/massalagros.com\/fr\/blog\/espace-gourmand\/","name":"Espace gourmand : notre s\u00e9lection - Blog | Mas Salagros","isPartOf":{"@id":"https:\/\/www.massalagros.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/massalagros.com\/fr\/blog\/espace-gourmand\/#primaryimage"},"image":{"@id":"https:\/\/massalagros.com\/fr\/blog\/espace-gourmand\/#primaryimage"},"thumbnailUrl":"https:\/\/massalagros.com\/wp-content\/uploads\/2023\/04\/espace-gourmand.jpg","datePublished":"2023-04-19T09:00:54+00:00","description":"D\u00e9couvrez l\u2019espace gourmand du Mas Salagros, o\u00f9 l\u2019on y propose une cuisine biologique du terroir pour une exp\u00e9rience culinaire unique.","breadcrumb":{"@id":"https:\/\/massalagros.com\/fr\/blog\/espace-gourmand\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/massalagros.com\/fr\/blog\/espace-gourmand\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/massalagros.com\/fr\/blog\/espace-gourmand\/#primaryimage","url":"https:\/\/massalagros.com\/wp-content\/uploads\/2023\/04\/espace-gourmand.jpg","contentUrl":"https:\/\/massalagros.com\/wp-content\/uploads\/2023\/04\/espace-gourmand.jpg","width":800,"height":412,"caption":"espace gourmand"},{"@type":"BreadcrumbList","@id":"https:\/\/massalagros.com\/fr\/blog\/espace-gourmand\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/massalagros.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Espace gourmand et cuisine biologique au Mas Salagros"}]},{"@type":"WebSite","@id":"https:\/\/www.massalagros.com\/fr\/#website","url":"https:\/\/www.massalagros.com\/fr\/","name":"Mas Salagros","description":"EcoResort de lujo en Barcelona - Vallromanes","publisher":{"@id":"https:\/\/www.massalagros.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.massalagros.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.massalagros.com\/fr\/#organization","name":"MAS SALAGROS HOTEL ECORESORT","url":"https:\/\/www.massalagros.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.massalagros.com\/fr\/#\/schema\/logo\/image\/","url":"\/wp-content\/uploads\/2018\/05\/IMG_0116.jpg","contentUrl":"\/wp-content\/uploads\/2018\/05\/IMG_0116.jpg","width":2000,"height":1333,"caption":"MAS SALAGROS HOTEL ECORESORT"},"image":{"@id":"https:\/\/www.massalagros.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MasSalagros\/","https:\/\/x.com\/MasSalagros","https:\/\/www.instagram.com\/massalagrosecoresort\/"]},{"@type":"Person","@id":"https:\/\/www.massalagros.com\/fr\/#\/schema\/person\/3773f2547b939ef33bcc2be351034752","name":"Mariona Mallafr\u00e9","description":"\u00a1Hola! Soy Mariona. Luego de graduarme en Publicidad y Relaciones P\u00fablicas en la Universidad Abat Oliba CEU, he acumulado a\u00f1os de experiencia trabajando en agencias de publicidad y comunicaci\u00f3n, especializ\u00e1ndome en los sectores de Turismo y Lifestyle. Mi trayectoria dio un giro emocionante a principios de 2017 al unirme al equipo de Mas Salagros, un proyecto innovador que lidera el turismo ecol\u00f3gico y sostenible en Espa\u00f1a. En este contexto, he tenido la responsabilidad de concebir, dirigir e implementar toda la estrategia de comunicaci\u00f3n y marketing. Lo que m\u00e1s me apasiona de mi labor en Mas Salagros es la oportunidad de desarrollar estrategias de comunicaci\u00f3n y marketing que contribuyan a nuestro principal objetivo: fomentar el turismo responsable y sostenible. Esta pasi\u00f3n me llev\u00f3 a complementar mis estudios con un m\u00e1ster en la prestigiosa escuela de negocios ISDI, especializada en la era digital, con el prop\u00f3sito de seguir aportando conocimientos digitales a un negocio tan innovador. Trabajar en Mas Salagros me permite crear experiencias personalizadas para cada cliente, haci\u00e9ndolos sentir \u00fanicos y cuidando hasta el \u00faltimo detalle. Este enfoque potencia mi creatividad, ya que las posibilidades son verdaderamente ilimitadas. Estoy emocionada por seguir contribuyendo al crecimiento de un negocio que comparte mis valores de sostenibilidad y excelencia en el servicio.","url":"https:\/\/massalagros.com\/fr\/blog\/author\/mariona\/"}]}},"_links":{"self":[{"href":"https:\/\/massalagros.com\/fr\/wp-json\/wp\/v2\/posts\/20931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/massalagros.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/massalagros.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/massalagros.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/massalagros.com\/fr\/wp-json\/wp\/v2\/comments?post=20931"}],"version-history":[{"count":2,"href":"https:\/\/massalagros.com\/fr\/wp-json\/wp\/v2\/posts\/20931\/revisions"}],"predecessor-version":[{"id":20934,"href":"https:\/\/massalagros.com\/fr\/wp-json\/wp\/v2\/posts\/20931\/revisions\/20934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/massalagros.com\/fr\/wp-json\/wp\/v2\/media\/21120"}],"wp:attachment":[{"href":"https:\/\/massalagros.com\/fr\/wp-json\/wp\/v2\/media?parent=20931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/massalagros.com\/fr\/wp-json\/wp\/v2\/categories?post=20931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/massalagros.com\/fr\/wp-json\/wp\/v2\/tags?post=20931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}