{"id":7102,"date":"2020-05-26T10:01:31","date_gmt":"2020-05-26T10:01:31","guid":{"rendered":"https:\/\/massalagros.com\/room-service\/"},"modified":"2026-05-06T21:13:46","modified_gmt":"2026-05-06T21:13:46","slug":"room-service","status":"publish","type":"page","link":"https:\/\/massalagros.com\/fr\/room-service\/","title":{"rendered":"Room service"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":9500,"parent":0,"menu_order":97,"comment_status":"closed","ping_status":"closed","template":"views\/template-carta.blade.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-7102","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Room Service - Cuisine | Mas Salagros EcoResort<\/title>\n<meta name=\"description\" content=\"Profitez de notre service de chambre. Dans le menu, vous trouverez une s\u00e9lection de la gastronomie bio et saisonni\u00e8re de nos restaurants.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/massalagros.com\/fr\/room-service\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Room Service - Cuisine | Mas Salagros EcoResort\" \/>\n<meta property=\"og:description\" content=\"Profitez de notre service de chambre. Dans le menu, vous trouverez une s\u00e9lection de la gastronomie bio et saisonni\u00e8re de nos restaurants.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/massalagros.com\/fr\/room-service\/\" \/>\n<meta property=\"og:site_name\" content=\"Mas Salagros\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MasSalagros\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T21:13:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/massalagros.com\/wp-content\/uploads\/2021\/03\/Room-service-Mas-Salagros-EcoResort.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1560\" \/>\n\t<meta property=\"og:image:height\" content=\"1040\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MasSalagros\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/massalagros.com\\\/fr\\\/room-service\\\/\",\"url\":\"https:\\\/\\\/massalagros.com\\\/fr\\\/room-service\\\/\",\"name\":\"Room Service - Cuisine | Mas Salagros EcoResort\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/massalagros.com\\\/fr\\\/room-service\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/massalagros.com\\\/fr\\\/room-service\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/massalagros.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Room-service-Mas-Salagros-EcoResort.jpg\",\"datePublished\":\"2020-05-26T10:01:31+00:00\",\"dateModified\":\"2026-05-06T21:13:46+00:00\",\"description\":\"Profitez de notre service de chambre. Dans le menu, vous trouverez une s\u00e9lection de la gastronomie bio et saisonni\u00e8re de nos restaurants.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/massalagros.com\\\/fr\\\/room-service\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/massalagros.com\\\/fr\\\/room-service\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/massalagros.com\\\/fr\\\/room-service\\\/#primaryimage\",\"url\":\"https:\\\/\\\/massalagros.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Room-service-Mas-Salagros-EcoResort.jpg\",\"contentUrl\":\"https:\\\/\\\/massalagros.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Room-service-Mas-Salagros-EcoResort.jpg\",\"width\":1560,\"height\":1040,\"caption\":\"room service Mas Salagros EcoResort\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/massalagros.com\\\/fr\\\/room-service\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/massalagros.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Room service\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.massalagros.com\\\/fr\\\/\",\"name\":\"Mas Salagros\",\"description\":\"EcoResort de lujo en Barcelona - Vallromanes\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.massalagros.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/fr\\\/#organization\",\"name\":\"MAS SALAGROS HOTEL ECORESORT\",\"url\":\"https:\\\/\\\/www.massalagros.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/IMG_0116.jpg\",\"contentUrl\":\"\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/IMG_0116.jpg\",\"width\":2000,\"height\":1333,\"caption\":\"MAS SALAGROS HOTEL ECORESORT\"},\"image\":{\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MasSalagros\\\/\",\"https:\\\/\\\/x.com\\\/MasSalagros\",\"https:\\\/\\\/www.instagram.com\\\/massalagrosecoresort\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Room Service - Cuisine | Mas Salagros EcoResort","description":"Profitez de notre service de chambre. Dans le menu, vous trouverez une s\u00e9lection de la gastronomie bio et saisonni\u00e8re de nos restaurants.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/massalagros.com\/fr\/room-service\/","og_locale":"fr_FR","og_type":"article","og_title":"Room Service - Cuisine | Mas Salagros EcoResort","og_description":"Profitez de notre service de chambre. Dans le menu, vous trouverez une s\u00e9lection de la gastronomie bio et saisonni\u00e8re de nos restaurants.","og_url":"https:\/\/massalagros.com\/fr\/room-service\/","og_site_name":"Mas Salagros","article_publisher":"https:\/\/www.facebook.com\/MasSalagros\/","article_modified_time":"2026-05-06T21:13:46+00:00","og_image":[{"width":1560,"height":1040,"url":"https:\/\/massalagros.com\/wp-content\/uploads\/2021\/03\/Room-service-Mas-Salagros-EcoResort.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MasSalagros","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/massalagros.com\/fr\/room-service\/","url":"https:\/\/massalagros.com\/fr\/room-service\/","name":"Room Service - Cuisine | Mas Salagros EcoResort","isPartOf":{"@id":"https:\/\/www.massalagros.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/massalagros.com\/fr\/room-service\/#primaryimage"},"image":{"@id":"https:\/\/massalagros.com\/fr\/room-service\/#primaryimage"},"thumbnailUrl":"https:\/\/massalagros.com\/wp-content\/uploads\/2021\/03\/Room-service-Mas-Salagros-EcoResort.jpg","datePublished":"2020-05-26T10:01:31+00:00","dateModified":"2026-05-06T21:13:46+00:00","description":"Profitez de notre service de chambre. Dans le menu, vous trouverez une s\u00e9lection de la gastronomie bio et saisonni\u00e8re de nos restaurants.","breadcrumb":{"@id":"https:\/\/massalagros.com\/fr\/room-service\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/massalagros.com\/fr\/room-service\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/massalagros.com\/fr\/room-service\/#primaryimage","url":"https:\/\/massalagros.com\/wp-content\/uploads\/2021\/03\/Room-service-Mas-Salagros-EcoResort.jpg","contentUrl":"https:\/\/massalagros.com\/wp-content\/uploads\/2021\/03\/Room-service-Mas-Salagros-EcoResort.jpg","width":1560,"height":1040,"caption":"room service Mas Salagros EcoResort"},{"@type":"BreadcrumbList","@id":"https:\/\/massalagros.com\/fr\/room-service\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/massalagros.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Room service"}]},{"@type":"WebSite","@id":"https:\/\/www.massalagros.com\/fr\/#website","url":"https:\/\/www.massalagros.com\/fr\/","name":"Mas Salagros","description":"EcoResort de lujo en Barcelona - Vallromanes","publisher":{"@id":"https:\/\/www.massalagros.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.massalagros.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.massalagros.com\/fr\/#organization","name":"MAS SALAGROS HOTEL ECORESORT","url":"https:\/\/www.massalagros.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.massalagros.com\/fr\/#\/schema\/logo\/image\/","url":"\/wp-content\/uploads\/2018\/05\/IMG_0116.jpg","contentUrl":"\/wp-content\/uploads\/2018\/05\/IMG_0116.jpg","width":2000,"height":1333,"caption":"MAS SALAGROS HOTEL ECORESORT"},"image":{"@id":"https:\/\/www.massalagros.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MasSalagros\/","https:\/\/x.com\/MasSalagros","https:\/\/www.instagram.com\/massalagrosecoresort\/"]}]}},"_links":{"self":[{"href":"https:\/\/massalagros.com\/fr\/wp-json\/wp\/v2\/pages\/7102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/massalagros.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/massalagros.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/massalagros.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/massalagros.com\/fr\/wp-json\/wp\/v2\/comments?post=7102"}],"version-history":[{"count":5,"href":"https:\/\/massalagros.com\/fr\/wp-json\/wp\/v2\/pages\/7102\/revisions"}],"predecessor-version":[{"id":31152,"href":"https:\/\/massalagros.com\/fr\/wp-json\/wp\/v2\/pages\/7102\/revisions\/31152"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/massalagros.com\/fr\/wp-json\/wp\/v2\/media\/9500"}],"wp:attachment":[{"href":"https:\/\/massalagros.com\/fr\/wp-json\/wp\/v2\/media?parent=7102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}