{"id":3,"name":"Mariona Mallafr\u00e9","url":"","description":"\u00a1Hola! Soy Mariona.\r\nLuego de graduarme en Publicidad y Relaciones P\u00fablicas en la Universidad Abat Oliba CEU, he acumulado a\u00f1os de experiencia trabajando en agencias de publicidad y comunicaci\u00f3n, especializ\u00e1ndome en los sectores de Turismo y Lifestyle.\r\nMi trayectoria dio un giro emocionante a principios de 2017 al unirme al equipo de Mas Salagros, un proyecto innovador que lidera el turismo ecol\u00f3gico y sostenible en Espa\u00f1a. En este contexto, he tenido la responsabilidad de concebir, dirigir e implementar toda la estrategia de comunicaci\u00f3n y marketing.\r\nLo que m\u00e1s me apasiona de mi labor en Mas Salagros es la oportunidad de desarrollar estrategias de comunicaci\u00f3n y marketing que contribuyan a nuestro principal objetivo: fomentar el turismo responsable y sostenible. Esta pasi\u00f3n me llev\u00f3 a complementar mis estudios con un m\u00e1ster en la prestigiosa escuela de negocios ISDI, especializada en la era digital, con el prop\u00f3sito de seguir aportando conocimientos digitales a un negocio tan innovador.\r\nTrabajar en Mas Salagros me permite crear experiencias personalizadas para cada cliente, haci\u00e9ndolos sentir \u00fanicos y cuidando hasta el \u00faltimo detalle. Este enfoque potencia mi creatividad, ya que las posibilidades son verdaderamente ilimitadas. Estoy emocionada por seguir contribuyendo al crecimiento de un negocio que comparte mis valores de sostenibilidad y excelencia en el servicio.","link":"https:\/\/massalagros.com\/en\/blog\/author\/mariona\/","slug":"mariona","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>, autor en Mas Salagros<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/massalagros.com\/en\/blog\/author\/mariona\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\", autor en Mas Salagros\" \/>\n<meta property=\"og:url\" content=\"https:\/\/massalagros.com\/blog\/author\/mariona\/\" \/>\n<meta property=\"og:site_name\" content=\"Mas Salagros\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/07644001a90fa744bdcafd21448cdbbb2d9de73db0b71716f875f617298c2708?s=500&d=mm&r=g\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MasSalagros\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/massalagros.com\\\/blog\\\/author\\\/mariona\\\/\",\"url\":\"https:\\\/\\\/massalagros.com\\\/blog\\\/author\\\/mariona\\\/\",\"name\":\", autor en Mas Salagros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/massalagros.com\\\/blog\\\/author\\\/mariona\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/massalagros.com\\\/blog\\\/author\\\/mariona\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/massalagros.com\\\/blog\\\/author\\\/mariona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/massalagros.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archivo de\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.massalagros.com\\\/en\\\/\",\"name\":\"Mas Salagros\",\"description\":\"EcoResort de lujo en Barcelona - Vallromanes\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.massalagros.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/en\\\/#organization\",\"name\":\"MAS SALAGROS HOTEL ECORESORT\",\"url\":\"https:\\\/\\\/www.massalagros.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/IMG_0116.jpg\",\"contentUrl\":\"\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/IMG_0116.jpg\",\"width\":2000,\"height\":1333,\"caption\":\"MAS SALAGROS HOTEL ECORESORT\"},\"image\":{\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MasSalagros\\\/\",\"https:\\\/\\\/x.com\\\/MasSalagros\",\"https:\\\/\\\/www.instagram.com\\\/massalagrosecoresort\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/en\\\/#\\\/schema\\\/person\\\/3773f2547b939ef33bcc2be351034752\",\"name\":\"Mariona Mallafr\u00e9\",\"description\":\"\u00a1Hola! Soy Mariona. Luego de graduarme en Publicidad y Relaciones P\u00fablicas en la Universidad Abat Oliba CEU, he acumulado a\u00f1os de experiencia trabajando en agencias de publicidad y comunicaci\u00f3n, especializ\u00e1ndome en los sectores de Turismo y Lifestyle. Mi trayectoria dio un giro emocionante a principios de 2017 al unirme al equipo de Mas Salagros, un proyecto innovador que lidera el turismo ecol\u00f3gico y sostenible en Espa\u00f1a. En este contexto, he tenido la responsabilidad de concebir, dirigir e implementar toda la estrategia de comunicaci\u00f3n y marketing. Lo que m\u00e1s me apasiona de mi labor en Mas Salagros es la oportunidad de desarrollar estrategias de comunicaci\u00f3n y marketing que contribuyan a nuestro principal objetivo: fomentar el turismo responsable y sostenible. Esta pasi\u00f3n me llev\u00f3 a complementar mis estudios con un m\u00e1ster en la prestigiosa escuela de negocios ISDI, especializada en la era digital, con el prop\u00f3sito de seguir aportando conocimientos digitales a un negocio tan innovador. Trabajar en Mas Salagros me permite crear experiencias personalizadas para cada cliente, haci\u00e9ndolos sentir \u00fanicos y cuidando hasta el \u00faltimo detalle. Este enfoque potencia mi creatividad, ya que las posibilidades son verdaderamente ilimitadas. Estoy emocionada por seguir contribuyendo al crecimiento de un negocio que comparte mis valores de sostenibilidad y excelencia en el servicio.\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/massalagros.com\\\/blog\\\/author\\\/mariona\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":", autor en Mas Salagros","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/massalagros.com\/en\/blog\/author\/mariona\/","og_locale":"en_US","og_type":"profile","og_title":", autor en Mas Salagros","og_url":"https:\/\/massalagros.com\/blog\/author\/mariona\/","og_site_name":"Mas Salagros","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/07644001a90fa744bdcafd21448cdbbb2d9de73db0b71716f875f617298c2708?s=500&d=mm&r=g","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@MasSalagros","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/massalagros.com\/blog\/author\/mariona\/","url":"https:\/\/massalagros.com\/blog\/author\/mariona\/","name":", autor en Mas Salagros","isPartOf":{"@id":"https:\/\/www.massalagros.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/massalagros.com\/blog\/author\/mariona\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/massalagros.com\/blog\/author\/mariona\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/massalagros.com\/blog\/author\/mariona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/massalagros.com\/en\/"},{"@type":"ListItem","position":2,"name":"Archivo de"}]},{"@type":"WebSite","@id":"https:\/\/www.massalagros.com\/en\/#website","url":"https:\/\/www.massalagros.com\/en\/","name":"Mas Salagros","description":"EcoResort de lujo en Barcelona - Vallromanes","publisher":{"@id":"https:\/\/www.massalagros.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.massalagros.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.massalagros.com\/en\/#organization","name":"MAS SALAGROS HOTEL ECORESORT","url":"https:\/\/www.massalagros.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.massalagros.com\/en\/#\/schema\/logo\/image\/","url":"\/wp-content\/uploads\/2018\/05\/IMG_0116.jpg","contentUrl":"\/wp-content\/uploads\/2018\/05\/IMG_0116.jpg","width":2000,"height":1333,"caption":"MAS SALAGROS HOTEL ECORESORT"},"image":{"@id":"https:\/\/www.massalagros.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MasSalagros\/","https:\/\/x.com\/MasSalagros","https:\/\/www.instagram.com\/massalagrosecoresort\/"]},{"@type":"Person","@id":"https:\/\/www.massalagros.com\/en\/#\/schema\/person\/3773f2547b939ef33bcc2be351034752","name":"Mariona Mallafr\u00e9","description":"\u00a1Hola! Soy Mariona. Luego de graduarme en Publicidad y Relaciones P\u00fablicas en la Universidad Abat Oliba CEU, he acumulado a\u00f1os de experiencia trabajando en agencias de publicidad y comunicaci\u00f3n, especializ\u00e1ndome en los sectores de Turismo y Lifestyle. Mi trayectoria dio un giro emocionante a principios de 2017 al unirme al equipo de Mas Salagros, un proyecto innovador que lidera el turismo ecol\u00f3gico y sostenible en Espa\u00f1a. En este contexto, he tenido la responsabilidad de concebir, dirigir e implementar toda la estrategia de comunicaci\u00f3n y marketing. Lo que m\u00e1s me apasiona de mi labor en Mas Salagros es la oportunidad de desarrollar estrategias de comunicaci\u00f3n y marketing que contribuyan a nuestro principal objetivo: fomentar el turismo responsable y sostenible. Esta pasi\u00f3n me llev\u00f3 a complementar mis estudios con un m\u00e1ster en la prestigiosa escuela de negocios ISDI, especializada en la era digital, con el prop\u00f3sito de seguir aportando conocimientos digitales a un negocio tan innovador. Trabajar en Mas Salagros me permite crear experiencias personalizadas para cada cliente, haci\u00e9ndolos sentir \u00fanicos y cuidando hasta el \u00faltimo detalle. Este enfoque potencia mi creatividad, ya que las posibilidades son verdaderamente ilimitadas. Estoy emocionada por seguir contribuyendo al crecimiento de un negocio que comparte mis valores de sostenibilidad y excelencia en el servicio.","mainEntityOfPage":{"@id":"https:\/\/massalagros.com\/blog\/author\/mariona\/"}}]}},"is_super_admin":false,"woocommerce_meta":{"variable_product_tour_shown":"","activity_panel_inbox_last_read":"","activity_panel_reviews_last_read":"","categories_report_columns":"","coupons_report_columns":"","customers_report_columns":"","orders_report_columns":"","products_report_columns":"","revenue_report_columns":"","taxes_report_columns":"","variations_report_columns":"","dashboard_sections":"","dashboard_chart_type":"","dashboard_chart_interval":"","dashboard_leaderboard_rows":"","order_attribution_install_banner_dismissed":"","scheduled_updates_promotion_notice_dismissed":"","homepage_layout":"","homepage_stats":"","task_list_tracked_started_tasks":"","android_app_banner_dismissed":"","launch_your_store_tour_hidden":"","coming_soon_banner_dismissed":""},"_links":{"self":[{"href":"https:\/\/massalagros.com\/en\/wp-json\/wp\/v2\/users\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/massalagros.com\/en\/wp-json\/wp\/v2\/users"}]}}