{"id":1335,"date":"2018-05-14T09:29:19","date_gmt":"2018-05-14T09:29:19","guid":{"rendered":"https:\/\/massalagros.com\/?page_id=1335"},"modified":"2023-01-12T13:01:15","modified_gmt":"2023-01-12T13:01:15","slug":"legal-notice","status":"publish","type":"page","link":"https:\/\/massalagros.com\/en\/legal-notice\/","title":{"rendered":"Legal notice"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":189,"comment_status":"closed","ping_status":"closed","template":"views\/template-full-options.blade.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1335","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aviso legal \u2013 EcoResort Mas Salagros<\/title>\n<meta name=\"description\" content=\"El presente documento tiene por finalidad regular las NORMAS DE USO y salvaguardar la PROTECCI\u00d3N DE LOS USUARIOS de massalagros.com.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/massalagros.com\/en\/legal-notice\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aviso legal \u2013 EcoResort Mas Salagros\" \/>\n<meta property=\"og:description\" content=\"El presente documento tiene por finalidad regular las NORMAS DE USO y salvaguardar la PROTECCI\u00d3N DE LOS USUARIOS de massalagros.com.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/massalagros.com\/en\/legal-notice\/\" \/>\n<meta property=\"og:site_name\" content=\"Mas Salagros\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MasSalagros\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-12T13:01:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MasSalagros\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/massalagros.com\\\/en\\\/legal-notice\\\/\",\"url\":\"https:\\\/\\\/massalagros.com\\\/en\\\/legal-notice\\\/\",\"name\":\"Aviso legal \u2013 EcoResort Mas Salagros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/en\\\/#website\"},\"datePublished\":\"2018-05-14T09:29:19+00:00\",\"dateModified\":\"2023-01-12T13:01:15+00:00\",\"description\":\"El presente documento tiene por finalidad regular las NORMAS DE USO y salvaguardar la PROTECCI\u00d3N DE LOS USUARIOS de massalagros.com.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/massalagros.com\\\/en\\\/legal-notice\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/massalagros.com\\\/en\\\/legal-notice\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/massalagros.com\\\/en\\\/legal-notice\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/massalagros.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Legal notice\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.massalagros.com\\\/en\\\/\",\"name\":\"Mas Salagros\",\"description\":\"EcoResort de lujo en Barcelona - Vallromanes\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.massalagros.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/en\\\/#organization\",\"name\":\"MAS SALAGROS HOTEL ECORESORT\",\"url\":\"https:\\\/\\\/www.massalagros.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/IMG_0116.jpg\",\"contentUrl\":\"\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/IMG_0116.jpg\",\"width\":2000,\"height\":1333,\"caption\":\"MAS SALAGROS HOTEL ECORESORT\"},\"image\":{\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MasSalagros\\\/\",\"https:\\\/\\\/x.com\\\/MasSalagros\",\"https:\\\/\\\/www.instagram.com\\\/massalagrosecoresort\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aviso legal \u2013 EcoResort Mas Salagros","description":"El presente documento tiene por finalidad regular las NORMAS DE USO y salvaguardar la PROTECCI\u00d3N DE LOS USUARIOS de massalagros.com.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/massalagros.com\/en\/legal-notice\/","og_locale":"en_US","og_type":"article","og_title":"Aviso legal \u2013 EcoResort Mas Salagros","og_description":"El presente documento tiene por finalidad regular las NORMAS DE USO y salvaguardar la PROTECCI\u00d3N DE LOS USUARIOS de massalagros.com.","og_url":"https:\/\/massalagros.com\/en\/legal-notice\/","og_site_name":"Mas Salagros","article_publisher":"https:\/\/www.facebook.com\/MasSalagros\/","article_modified_time":"2023-01-12T13:01:15+00:00","twitter_card":"summary_large_image","twitter_site":"@MasSalagros","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/massalagros.com\/en\/legal-notice\/","url":"https:\/\/massalagros.com\/en\/legal-notice\/","name":"Aviso legal \u2013 EcoResort Mas Salagros","isPartOf":{"@id":"https:\/\/www.massalagros.com\/en\/#website"},"datePublished":"2018-05-14T09:29:19+00:00","dateModified":"2023-01-12T13:01:15+00:00","description":"El presente documento tiene por finalidad regular las NORMAS DE USO y salvaguardar la PROTECCI\u00d3N DE LOS USUARIOS de massalagros.com.","breadcrumb":{"@id":"https:\/\/massalagros.com\/en\/legal-notice\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/massalagros.com\/en\/legal-notice\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/massalagros.com\/en\/legal-notice\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/massalagros.com\/en\/"},{"@type":"ListItem","position":2,"name":"Legal notice"}]},{"@type":"WebSite","@id":"https:\/\/www.massalagros.com\/en\/#website","url":"https:\/\/www.massalagros.com\/en\/","name":"Mas Salagros","description":"EcoResort de lujo en Barcelona - Vallromanes","publisher":{"@id":"https:\/\/www.massalagros.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.massalagros.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.massalagros.com\/en\/#organization","name":"MAS SALAGROS HOTEL ECORESORT","url":"https:\/\/www.massalagros.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.massalagros.com\/en\/#\/schema\/logo\/image\/","url":"\/wp-content\/uploads\/2018\/05\/IMG_0116.jpg","contentUrl":"\/wp-content\/uploads\/2018\/05\/IMG_0116.jpg","width":2000,"height":1333,"caption":"MAS SALAGROS HOTEL ECORESORT"},"image":{"@id":"https:\/\/www.massalagros.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MasSalagros\/","https:\/\/x.com\/MasSalagros","https:\/\/www.instagram.com\/massalagrosecoresort\/"]}]}},"_links":{"self":[{"href":"https:\/\/massalagros.com\/en\/wp-json\/wp\/v2\/pages\/1335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/massalagros.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/massalagros.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/massalagros.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/massalagros.com\/en\/wp-json\/wp\/v2\/comments?post=1335"}],"version-history":[{"count":3,"href":"https:\/\/massalagros.com\/en\/wp-json\/wp\/v2\/pages\/1335\/revisions"}],"predecessor-version":[{"id":19273,"href":"https:\/\/massalagros.com\/en\/wp-json\/wp\/v2\/pages\/1335\/revisions\/19273"}],"wp:attachment":[{"href":"https:\/\/massalagros.com\/en\/wp-json\/wp\/v2\/media?parent=1335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}