{"id":2,"name":"Quico Domingo","url":"http:\/\/www.mortensen.cat","description":"","link":"https:\/\/massalagros.com\/de\/blog\/author\/mortensen\/","slug":"mortensen","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>, autor en Mas Salagros<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.massalagros.com\/de\/blog\/author\/mortensen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\", autor en Mas Salagros\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.massalagros.com\/blog\/author\/mortensen\/\" \/>\n<meta property=\"og:site_name\" content=\"Mas Salagros\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/4309fa8b4f99ed9d3913b2f91d84e5b6?s=500&d=mm&r=g\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MasSalagros\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/blog\\\/author\\\/mortensen\\\/\",\"url\":\"https:\\\/\\\/www.massalagros.com\\\/blog\\\/author\\\/mortensen\\\/\",\"name\":\", autor en Mas Salagros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/blog\\\/author\\\/mortensen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.massalagros.com\\\/blog\\\/author\\\/mortensen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/blog\\\/author\\\/mortensen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/massalagros.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archivo de\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.massalagros.com\\\/de\\\/\",\"name\":\"Mas Salagros\",\"description\":\"EcoResort de lujo en Barcelona - Vallromanes\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.massalagros.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/de\\\/#organization\",\"name\":\"MAS SALAGROS HOTEL ECORESORT\",\"url\":\"https:\\\/\\\/www.massalagros.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/IMG_0116.jpg\",\"contentUrl\":\"\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/IMG_0116.jpg\",\"width\":2000,\"height\":1333,\"caption\":\"MAS SALAGROS HOTEL ECORESORT\"},\"image\":{\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MasSalagros\\\/\",\"https:\\\/\\\/x.com\\\/MasSalagros\",\"https:\\\/\\\/www.instagram.com\\\/massalagrosecoresort\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/de\\\/#\\\/schema\\\/person\\\/68bbc1e1dbc982f226990c099467eb29\",\"name\":\"Quico Domingo\",\"sameAs\":[\"http:\\\/\\\/www.mortensen.cat\"],\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.massalagros.com\\\/blog\\\/author\\\/mortensen\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":", autor en Mas Salagros","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.massalagros.com\/de\/blog\/author\/mortensen\/","og_locale":"de_DE","og_type":"profile","og_title":", autor en Mas Salagros","og_url":"https:\/\/www.massalagros.com\/blog\/author\/mortensen\/","og_site_name":"Mas Salagros","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/4309fa8b4f99ed9d3913b2f91d84e5b6?s=500&d=mm&r=g","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@MasSalagros","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/www.massalagros.com\/blog\/author\/mortensen\/","url":"https:\/\/www.massalagros.com\/blog\/author\/mortensen\/","name":", autor en Mas Salagros","isPartOf":{"@id":"https:\/\/www.massalagros.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/www.massalagros.com\/blog\/author\/mortensen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.massalagros.com\/blog\/author\/mortensen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.massalagros.com\/blog\/author\/mortensen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/massalagros.com\/de\/"},{"@type":"ListItem","position":2,"name":"Archivo de"}]},{"@type":"WebSite","@id":"https:\/\/www.massalagros.com\/de\/#website","url":"https:\/\/www.massalagros.com\/de\/","name":"Mas Salagros","description":"EcoResort de lujo en Barcelona - Vallromanes","publisher":{"@id":"https:\/\/www.massalagros.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.massalagros.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.massalagros.com\/de\/#organization","name":"MAS SALAGROS HOTEL ECORESORT","url":"https:\/\/www.massalagros.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.massalagros.com\/de\/#\/schema\/logo\/image\/","url":"\/wp-content\/uploads\/2018\/05\/IMG_0116.jpg","contentUrl":"\/wp-content\/uploads\/2018\/05\/IMG_0116.jpg","width":2000,"height":1333,"caption":"MAS SALAGROS HOTEL ECORESORT"},"image":{"@id":"https:\/\/www.massalagros.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MasSalagros\/","https:\/\/x.com\/MasSalagros","https:\/\/www.instagram.com\/massalagrosecoresort\/"]},{"@type":"Person","@id":"https:\/\/www.massalagros.com\/de\/#\/schema\/person\/68bbc1e1dbc982f226990c099467eb29","name":"Quico Domingo","sameAs":["http:\/\/www.mortensen.cat"],"mainEntityOfPage":{"@id":"https:\/\/www.massalagros.com\/blog\/author\/mortensen\/"}}]}},"is_super_admin":true,"woocommerce_meta":{"variable_product_tour_shown":"yes","activity_panel_inbox_last_read":"","activity_panel_reviews_last_read":"","categories_report_columns":"","coupons_report_columns":"","customers_report_columns":"","orders_report_columns":"","products_report_columns":"","revenue_report_columns":"","taxes_report_columns":"","variations_report_columns":"","dashboard_sections":"","dashboard_chart_type":"","dashboard_chart_interval":"","dashboard_leaderboard_rows":"","order_attribution_install_banner_dismissed":"","scheduled_updates_promotion_notice_dismissed":"","homepage_layout":"","homepage_stats":"","task_list_tracked_started_tasks":"","android_app_banner_dismissed":"","launch_your_store_tour_hidden":"","coming_soon_banner_dismissed":"yes"},"_links":{"self":[{"href":"https:\/\/massalagros.com\/de\/wp-json\/wp\/v2\/users\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/massalagros.com\/de\/wp-json\/wp\/v2\/users"}]}}